{"id":1458,"date":"2022-06-13T15:23:03","date_gmt":"2022-06-13T13:23:03","guid":{"rendered":"https:\/\/assografici.it\/?p=4474"},"modified":"2022-06-13T15:26:57","modified_gmt":"2022-06-13T13:26:57","slug":"oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature","status":"publish","type":"post","link":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/","title":{"rendered":"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature"},"content":{"rendered":"<p>La <strong>deadline per candidare la propria azienda agli Oscar della Stampa<\/strong>, dal 1987 il pi\u00f9 ambito riconoscimento all\u2019eccellenza dell\u2019industria della stampa e del converting in Italia, \u00e8 stata\u00a0<strong>prorogata al 3 luglio 2022<\/strong>\u00a0cos\u00ec da dare modo a tutte le aziende interessate di partecipare.<\/p>\n<p>L\u2019edizione 2022 degli Oscar della Stampa, che culminer\u00e0 nella\u00a0<strong>cerimonia di premiazione del prossimo 2 dicembre<\/strong>,\u00a0\u00e8 la prima organizzata da Stratego Group in partnership con l\u2019Unione GCT Milano: un sodalizio strategico tra l\u2019Associazione milanese e una manifestazione che su quel territorio \u00e8 nata e poi nel tempo si \u00e8 sviluppata, garantendo alle aziende una visibilit\u00e0 e un protagonismo nazionale.<\/p>\n<p>Il coinvolgimento diretto dell\u2019Unione GCT Milano porta con s\u00e9 un supporto operativo diretto anche di Assografici che, insieme alla Federazione Carta e Grafica, patrocina da anni il Premio. Tante sono le novit\u00e0 di questa edizione: in particolare sono state previste nuove categorie (tutti i settori del packaging, oltre a quelli della stampa grafica e commerciale, sono ben rappresentati) e rivisti i criteri con i quali la Giuria esprimer\u00e0 le proprie valutazioni.<\/p>\n<p><strong>Possono concorrere agli Oscar tutte le aziende con sede produttiva in Italia<\/strong>\u00a0e, da quest\u2019anno, sono le aziende che devono presentare la loro autocandidatura (non \u00e8 pi\u00f9 sufficiente la sola segnalazione di terzi).<\/p>\n<p><strong>Sono 8 le categorie<\/strong>\u00a0del Premio\u00a0tra le quali le aziende possono scegliere di candidarsi, coerentemente con gli investimenti effettuati e le attivit\u00e0 svolte negli ultimi 18 mesi:<\/p>\n<ul>\n<li>Best Cartotecnica<\/li>\n<li>Best Label Printer<\/li>\n<li>Best Digital Printer<\/li>\n<li>Best Wide &amp; Industrial printer<\/li>\n<li>Best Converter<\/li>\n<li>Best Publishing &amp; Commercial Printer<\/li>\n<li>Best Printer on Corrugated<\/li>\n<li>Best Nobilitazioni e Supporti Speciali<\/li>\n<\/ul>\n<p>Ci saranno poi alcuni\u00a0<strong>Premi Speciali<\/strong>, assegnati direttamente dalla Giuria,\u00a0composta da esperti del settore della stampa provenienti dal mondo dei media, della formazione, delle istituzioni, dei buyer e della comunicazione (anche il Vice Direttore di Assografici e dell\u2019Unione, Italo Vailati, ne far\u00e0 da questa edizione parte):<\/p>\n<ul>\n<li>Best Technology innovator<\/li>\n<li>Imprenditrice\/Imprenditore dell\u2019Anno<\/li>\n<li>Industria Grafica dell\u2019Anno<\/li>\n<\/ul>\n<p>Oltre a un\u00a0<strong>Premio alla Storia<\/strong>\u00a0che andr\u00e0 a un\u2019azienda che compia 100 anni.<\/p>\n<p>Le aziende\u00a0interessate a partecipare possono candidarsi\u00a0spontanea\u00admente compilando e inviando entro il\u00a0<strong>3 luglio 2022<\/strong>\u00a0la\u00a0<strong>Call for Entry<\/strong>, accessibile attraverso questo link:\u00a0<a href=\"https:\/\/4itgroup.mailmnta.com\/nl\/4ITGroup_page398.mn\" target=\"_blank\" rel=\"noopener\"><strong>Candidatura Oscar della Stampa<\/strong><\/a>.<\/p>\n<p><strong>Produttori di tecnologie e supporti non possono partecipare, se non in qualit\u00e0 di sponsor, ma possono comunque segnalare un\u2019azienda a loro giudizio meritevole, facendo s\u00ec che questa possa autocandidarsi ed entrare dunque in concorso.<\/strong><\/p>\n<p>Di seguito il link per segnalare un\u2019azienda meritevole:\u00a0<a href=\"https:\/\/4itgroup.mailmnta.com\/nl\/4ITGroup_page472.mn\" target=\"_blank\" rel=\"noopener\"><strong>Segnalazione aziende meritevoli<\/strong><\/a><\/p>\n<p>Al seguente link \u00e8 infine consultabile il Regolamento del Premio:\u00a0<a href=\"https:\/\/assografici.it\/wp-content\/uploads\/2022\/06\/OdS_Italia_Regolamento_extention.pdf\" target=\"_blank\" rel=\"noopener\"><strong>OdS_Italia_Regolamento<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La deadline per candidare la propria azienda agli Oscar della Stampa, dal 1987 il pi\u00f9 ambito riconoscimento all\u2019eccellenza dell\u2019industria della stampa e del converting in Italia, \u00e8 stata\u00a0prorogata al 3 luglio 2022\u00a0cos\u00ec da dare modo a tutte le aziende interessate di partecipare. L\u2019edizione 2022 degli Oscar della Stampa, che culminer\u00e0 nella\u00a0cerimonia di premiazione del prossimo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[149],"tags":[],"fonte":[91],"posizione":[64],"class_list":["post-1458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premi","fonte-federazione-carta-e-grafica-2","posizione-news-di-unione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature - Unione GCT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature - Unione GCT\" \/>\n<meta property=\"og:description\" content=\"La deadline per candidare la propria azienda agli Oscar della Stampa, dal 1987 il pi\u00f9 ambito riconoscimento all\u2019eccellenza dell\u2019industria della stampa e del converting in Italia, \u00e8 stata\u00a0prorogata al 3 luglio 2022\u00a0cos\u00ec da dare modo a tutte le aziende interessate di partecipare. L\u2019edizione 2022 degli Oscar della Stampa, che culminer\u00e0 nella\u00a0cerimonia di premiazione del prossimo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/\" \/>\n<meta property=\"og:site_name\" content=\"Unione GCT\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-13T13:23:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-13T13:26:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2022\/06\/ODS-COVER-def.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1337\" \/>\n\t<meta property=\"og:image:height\" content=\"1136\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ruggero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ruggero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/\"},\"author\":{\"name\":\"ruggero\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#\\\/schema\\\/person\\\/d9e69f409f0f83e24b4b3e2d331a3589\"},\"headline\":\"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature\",\"datePublished\":\"2022-06-13T13:23:03+00:00\",\"dateModified\":\"2022-06-13T13:26:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unione.gct.mi.it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/ODS-COVER-def.png\",\"articleSection\":[\"Premi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/\",\"url\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/\",\"name\":\"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature - Unione GCT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unione.gct.mi.it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/ODS-COVER-def.png\",\"datePublished\":\"2022-06-13T13:23:03+00:00\",\"dateModified\":\"2022-06-13T13:26:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unione.gct.mi.it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/ODS-COVER-def.png\",\"contentUrl\":\"https:\\\/\\\/unione.gct.mi.it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/ODS-COVER-def.png\",\"width\":1337,\"height\":1136},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unione.gct.mi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/\",\"name\":\"Unione GCT\",\"description\":\"Unione Grafici Cartotecnici Trasformatori Carta\",\"publisher\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#organization\",\"name\":\"Unione Industriali Grafici Cartotecnici Trasformatori carta e affini della provincia di Milano\",\"url\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unione.gct.mi.it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/01\\\/logo-unione.jpg\",\"contentUrl\":\"https:\\\/\\\/unione.gct.mi.it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/01\\\/logo-unione.jpg\",\"width\":348,\"height\":98,\"caption\":\"Unione Industriali Grafici Cartotecnici Trasformatori carta e affini della provincia di Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gct-milano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unione.gct.mi.it\\\/it\\\/#\\\/schema\\\/person\\\/d9e69f409f0f83e24b4b3e2d331a3589\",\"name\":\"ruggero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3161daf3d18a4a2a6a7cb7e278ccc5dda11e65c90c54e4b3367113765b8182ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3161daf3d18a4a2a6a7cb7e278ccc5dda11e65c90c54e4b3367113765b8182ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3161daf3d18a4a2a6a7cb7e278ccc5dda11e65c90c54e4b3367113765b8182ba?s=96&d=mm&r=g\",\"caption\":\"ruggero\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature - Unione GCT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/","og_locale":"it_IT","og_type":"article","og_title":"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature - Unione GCT","og_description":"La deadline per candidare la propria azienda agli Oscar della Stampa, dal 1987 il pi\u00f9 ambito riconoscimento all\u2019eccellenza dell\u2019industria della stampa e del converting in Italia, \u00e8 stata\u00a0prorogata al 3 luglio 2022\u00a0cos\u00ec da dare modo a tutte le aziende interessate di partecipare. L\u2019edizione 2022 degli Oscar della Stampa, che culminer\u00e0 nella\u00a0cerimonia di premiazione del prossimo [&hellip;]","og_url":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/","og_site_name":"Unione GCT","article_published_time":"2022-06-13T13:23:03+00:00","article_modified_time":"2022-06-13T13:26:57+00:00","og_image":[{"width":1337,"height":1136,"url":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2022\/06\/ODS-COVER-def.png","type":"image\/png"}],"author":"ruggero","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ruggero","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#article","isPartOf":{"@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/"},"author":{"name":"ruggero","@id":"https:\/\/unione.gct.mi.it\/it\/#\/schema\/person\/d9e69f409f0f83e24b4b3e2d331a3589"},"headline":"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature","datePublished":"2022-06-13T13:23:03+00:00","dateModified":"2022-06-13T13:26:57+00:00","mainEntityOfPage":{"@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/unione.gct.mi.it\/it\/#organization"},"image":{"@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#primaryimage"},"thumbnailUrl":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2022\/06\/ODS-COVER-def.png","articleSection":["Premi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/","url":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/","name":"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature - Unione GCT","isPartOf":{"@id":"https:\/\/unione.gct.mi.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#primaryimage"},"image":{"@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#primaryimage"},"thumbnailUrl":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2022\/06\/ODS-COVER-def.png","datePublished":"2022-06-13T13:23:03+00:00","dateModified":"2022-06-13T13:26:57+00:00","breadcrumb":{"@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#primaryimage","url":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2022\/06\/ODS-COVER-def.png","contentUrl":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2022\/06\/ODS-COVER-def.png","width":1337,"height":1136},{"@type":"BreadcrumbList","@id":"https:\/\/unione.gct.mi.it\/oscar-della-stampa-2022-prorogata-al-3-luglio-la-deadline-per-le-candidature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unione.gct.mi.it\/"},{"@type":"ListItem","position":2,"name":"Oscar della Stampa 2022: prorogata al 3 luglio la deadline per le candidature"}]},{"@type":"WebSite","@id":"https:\/\/unione.gct.mi.it\/it\/#website","url":"https:\/\/unione.gct.mi.it\/it\/","name":"Unione GCT","description":"Unione Grafici Cartotecnici Trasformatori Carta","publisher":{"@id":"https:\/\/unione.gct.mi.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unione.gct.mi.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/unione.gct.mi.it\/it\/#organization","name":"Unione Industriali Grafici Cartotecnici Trasformatori carta e affini della provincia di Milano","url":"https:\/\/unione.gct.mi.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/unione.gct.mi.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2021\/01\/logo-unione.jpg","contentUrl":"https:\/\/unione.gct.mi.it\/wp-content\/uploads\/sites\/3\/2021\/01\/logo-unione.jpg","width":348,"height":98,"caption":"Unione Industriali Grafici Cartotecnici Trasformatori carta e affini della provincia di Milano"},"image":{"@id":"https:\/\/unione.gct.mi.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/gct-milano"]},{"@type":"Person","@id":"https:\/\/unione.gct.mi.it\/it\/#\/schema\/person\/d9e69f409f0f83e24b4b3e2d331a3589","name":"ruggero","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3161daf3d18a4a2a6a7cb7e278ccc5dda11e65c90c54e4b3367113765b8182ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3161daf3d18a4a2a6a7cb7e278ccc5dda11e65c90c54e4b3367113765b8182ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3161daf3d18a4a2a6a7cb7e278ccc5dda11e65c90c54e4b3367113765b8182ba?s=96&d=mm&r=g","caption":"ruggero"}}]}},"_links":{"self":[{"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/posts\/1458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/comments?post=1458"}],"version-history":[{"count":1,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/posts\/1458\/revisions"}],"predecessor-version":[{"id":1460,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/posts\/1458\/revisions\/1460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/media\/1459"}],"wp:attachment":[{"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/media?parent=1458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/categories?post=1458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/tags?post=1458"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/fonte?post=1458"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/unione.gct.mi.it\/it\/wp-json\/wp\/v2\/posizione?post=1458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}